{"id":1032,"date":"2021-07-28T10:45:00","date_gmt":"2021-07-28T08:45:00","guid":{"rendered":"http:\/\/www.rocalba.es\/blog\/?p=1032"},"modified":"2021-07-22T12:52:49","modified_gmt":"2021-07-22T10:52:49","slug":"como-cuidar-las-plantas-acidofilas-como-la-hortensia","status":"publish","type":"post","link":"https:\/\/www.rocalba.es\/blog\/como-cuidar-las-plantas-acidofilas-como-la-hortensia\/","title":{"rendered":"\u00bfC\u00f3mo cuidar las plantas acid\u00f3filas como la hortensia?"},"content":{"rendered":"\n<p>De entre todas las <strong>plantas ornamentales que pueden decorar tu jard\u00edn, terraza, balc\u00f3n<\/strong> e incluso el interior de tu hogar, existen unas un poco particulares: <strong>las plantas acid\u00f3filas<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 es una planta acid\u00f3fila?<\/strong><\/h2>\n\n\n\n<p>Las plantas acid\u00f3filas se sienten c\u00f3modas cuando viven en un suelo \u00e1cido. El pH del suelo nos indica la alcalinidad o acidez del sustrato sobre el que sembraremos nuestras plantas ornamentales, hort\u00edcolas o arom\u00e1ticas.<\/p>\n\n\n\n<p><strong>Los suelos con un pH por debajo de 7 son considerados \u00e1cidos<\/strong>, los que cuentan con un pH de 7 se llaman neutros, y todos los que tienen un nivel superior a 7 se consideran b\u00e1sicos o alcalinos.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rocalba.es\/blog\/wp-content\/themes\/veen\/assets\/images\/transparent.gif\" data-lazy=\"true\" data-src=\"http:\/\/www.rocalba.es\/blog\/wp-content\/uploads\/hortensia-planta-ornamental-acidofila.jpg\" alt=\"\" class=\"wp-image-1035\" width=\"321\" height=\"230\" data-srcset=\"https:\/\/www.rocalba.es\/blog\/wp-content\/uploads\/hortensia-planta-ornamental-acidofila.jpg 480w, https:\/\/www.rocalba.es\/blog\/wp-content\/uploads\/hortensia-planta-ornamental-acidofila-300x215.jpg 300w, https:\/\/www.rocalba.es\/blog\/wp-content\/uploads\/hortensia-planta-ornamental-acidofila-100x72.jpg 100w\" data-sizes=\"(max-width: 321px) 100vw, 321px\" \/><\/figure><\/div>\n\n\n\n<p>Y tal vez alguien se preguntar\u00e1 <strong>\u00bfpueden cultivarse en el mismo sustrato plantas que cuentan con unas necesidades de pH de 4,5 en el suelo y otras que lo necesitan con un pH de 6?<\/strong> Lo cierto es que, aunque llamemos acid\u00f3filas a todas las que necesitan un suelo \u00e1cido, unas requieren de mayor acidez que otras en el sustrato, por lo que cuanto mejor cubramos las necesidades de acidez de cada planta, tendremos una mayor floraci\u00f3n en el caso de las plantas ornamentales, y mayores y mejores frutos y vegetales en nuestro huerto.<\/p>\n\n\n\n<p>Si, por el contrario, se cultivan plantas acid\u00f3filas en suelos alcalinos, en los casos m\u00e1s extremos, con mayor diferencia entre el pH necesario para la planta y el del suelo, en sus hojas se apreciar\u00e1 pronto la clorosis, y la planta enfermar\u00e1 para finalmente morir.<\/p>\n\n\n\n<p>Sin embargo, teniendo esto en cuenta no hay que preocuparse, pues existen <strong>m\u00faltiples manuales para poder consultar tablas de pH de todo tipo de cultivos<\/strong>, por lo que es sencillo conocer el tipo de sustrato que nuestras plantas requieren. <strong>Para medir el pH de tu suelo, necesitar\u00e1s un reactivo o medidor de pH, muy sencillos de utilizar.<\/strong><\/p>\n\n\n\n<p>Recomendamos que midas de vez en cuando el nivel de pH del suelo, para saber si necesitas acidificarlo empleando sulfato de hierro, para posteriormente volver a medir los niveles.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Plantas ornamentales acid\u00f3filas<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rocalba.es\/blog\/wp-content\/themes\/veen\/assets\/images\/transparent.gif\" data-lazy=\"true\" data-src=\"http:\/\/www.rocalba.es\/blog\/wp-content\/uploads\/brezo-planta-ornamental-acidofila.jpg\" alt=\"\" class=\"wp-image-1036\" width=\"243\" height=\"176\" data-srcset=\"https:\/\/www.rocalba.es\/blog\/wp-content\/uploads\/brezo-planta-ornamental-acidofila.jpg 480w, https:\/\/www.rocalba.es\/blog\/wp-content\/uploads\/brezo-planta-ornamental-acidofila-300x217.jpg 300w, https:\/\/www.rocalba.es\/blog\/wp-content\/uploads\/brezo-planta-ornamental-acidofila-100x72.jpg 100w\" data-sizes=\"(max-width: 243px) 100vw, 243px\" \/><\/figure><\/div>\n\n\n\n<p>De entre las m\u00e1s conocidas plantas decorativas de car\u00e1cter acid\u00f3filo, encontramos por supuesto la <strong>hortensia, pero tambi\u00e9n lo son las gardenias, camelias, brezos, <a href=\"https:\/\/www.rocalba.es\/es\/semillas-de-flores\/568-godetia.html?search_query=azalea&amp;results=1\" target=\"_blank\" rel=\"noreferrer noopener\">azaleas<\/a>, <a href=\"https:\/\/www.rocalba.es\/es\/arboles\/432-acebo.html\" target=\"_blank\" rel=\"noreferrer noopener\">acebos<\/a>, lirios de los valles e incluso los <a href=\"https:\/\/www.rocalba.es\/es\/search?controller=search&amp;orderby=position&amp;orderway=desc&amp;search_query=narciso&amp;tm_submit_search=\" target=\"_blank\" rel=\"noreferrer noopener\">narcisos<\/a>.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rocalba.es\/blog\/wp-content\/themes\/veen\/assets\/images\/transparent.gif\" data-lazy=\"true\" data-src=\"http:\/\/www.rocalba.es\/blog\/wp-content\/uploads\/camelia-planta-ornamental-acidofila.jpg\" alt=\"\" class=\"wp-image-1037\" width=\"270\" height=\"180\" data-srcset=\"https:\/\/www.rocalba.es\/blog\/wp-content\/uploads\/camelia-planta-ornamental-acidofila.jpg 480w, https:\/\/www.rocalba.es\/blog\/wp-content\/uploads\/camelia-planta-ornamental-acidofila-300x200.jpg 300w, https:\/\/www.rocalba.es\/blog\/wp-content\/uploads\/camelia-planta-ornamental-acidofila-100x67.jpg 100w\" data-sizes=\"(max-width: 270px) 100vw, 270px\" \/><\/figure><\/div>\n\n\n\n<p><strong>Estas plantas suelen preferir la semisombra y unos niveles de humedad constantes<\/strong>, por ello son muy habituales en muchas regiones del norte de Espa\u00f1a como macizos en los jardines, donde adem\u00e1s les viene muy bien el agua de la lluvia como riego, agua pura y no calc\u00e1rea como la del grifo.<\/p>\n\n\n\n<p>Lo ideal es, una vez estas plantas est\u00e1n acomodadas a un sustrato acorde a sus necesidades de acidez, <strong>no regarlas con \u201cagua dura\u201d o calc\u00e1rea<\/strong>. La soluci\u00f3n, si no tienes m\u00e1s remedio que regar con agua del grifo, es <strong>echar unas gotitas de vinagre a la regadera<\/strong> (el cual cuenta con un pH de 2,4 a 3,5 unidades de pH) para bajar el pH. Tambi\u00e9n sirven como alternativa para bajar el pH del \u201cagua dura\u201d el \u00e1cido c\u00edtrico o el sulfato de hierro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Plantas hort\u00edcolas acid\u00f3filas<\/strong><\/h2>\n\n\n\n<p>Pero no solamente encontramos plantas acid\u00f3filas en el jard\u00edn, <strong>tambi\u00e9n cuentas en tu huerto con una serie de plantas hort\u00edcolas y arom\u00e1ticas con car\u00e1cter acid\u00f3filo<\/strong>.<\/p>\n\n\n\n<p>Muchas de las plantas arom\u00e1ticas de tu huerta o <em>kitchen garden<\/em> tienen car\u00e1cter acid\u00f3filo. Es el caso de <strong>la <a href=\"https:\/\/www.rocalba.es\/es\/search?controller=search&amp;orderby=position&amp;orderway=desc&amp;search_query=albahaca&amp;tm_submit_search=\" target=\"_blank\" rel=\"noreferrer noopener\">albahaca<\/a>, el <a href=\"https:\/\/www.rocalba.es\/es\/aromaticas-y-medicinales\/666-Array.html\" target=\"_blank\" rel=\"noreferrer noopener\">eneldo<\/a>, el <a href=\"https:\/\/www.rocalba.es\/es\/search?controller=search&amp;orderby=position&amp;orderway=desc&amp;search_query=perejil&amp;tm_submit_search=\" target=\"_blank\" rel=\"noreferrer noopener\">perejil<\/a>, la <a href=\"https:\/\/www.rocalba.es\/es\/aromaticas-y-medicinales\/683-menta.html\" target=\"_blank\" rel=\"noreferrer noopener\">menta<\/a> o el <a href=\"https:\/\/www.rocalba.es\/es\/aromaticas-y-medicinales\/686-Array.html\" target=\"_blank\" rel=\"noreferrer noopener\">perifollo<\/a>.<\/strong><\/p>\n\n\n\n<p>Y en tu huerto, <strong>las <a href=\"https:\/\/www.rocalba.es\/es\/search?controller=search&amp;orderby=position&amp;orderway=desc&amp;search_query=bereNjena&amp;tm_submit_search=\" target=\"_blank\" rel=\"noreferrer noopener\">berenjenas<\/a>, <a href=\"https:\/\/www.rocalba.es\/es\/search?controller=search&amp;orderby=position&amp;orderway=desc&amp;search_query=melon&amp;tm_submit_search=\" target=\"_blank\" rel=\"noreferrer noopener\">melones<\/a>, <a href=\"https:\/\/www.rocalba.es\/es\/search?controller=search&amp;orderby=position&amp;orderway=desc&amp;search_query=calabaza&amp;tm_submit_search=\" target=\"_blank\" rel=\"noreferrer noopener\">calabazas<\/a>, <a href=\"https:\/\/www.rocalba.es\/es\/search?controller=search&amp;orderby=position&amp;orderway=desc&amp;search_query=calabacin&amp;tm_submit_search=\" target=\"_blank\" rel=\"noreferrer noopener\">calabacines<\/a>, <a href=\"https:\/\/www.rocalba.es\/es\/search?controller=search&amp;orderby=position&amp;orderway=desc&amp;search_query=alubia&amp;tm_submit_search=\" target=\"_blank\" rel=\"noreferrer noopener\">alubias<\/a> o <a href=\"https:\/\/www.rocalba.es\/es\/search?controller=search&amp;orderby=position&amp;orderway=desc&amp;search_query=lechuga&amp;tm_submit_search=\" target=\"_blank\" rel=\"noreferrer noopener\">lechugas<\/a>, tambi\u00e9n cuentan con necesidades acid\u00f3filas<\/strong>. Generalmente estas plantas no morir\u00e1n si no cuentan con un sustrato acid\u00f3filo, pero si adaptas su sustrato a sus necesidades de pH, aumentar\u00e1s las probabilidades de conseguir una buena cosecha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De entre todas las plantas ornamentales que pueden decorar tu jard\u00edn, terraza, balc\u00f3n e incluso el interior de tu hogar, existen unas un poco particulares: las plantas acid\u00f3filas.<\/p>\n","protected":false},"author":1,"featured_media":1033,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,14,20],"tags":[169,168,170,167,172,171],"_links":{"self":[{"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/posts\/1032"}],"collection":[{"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/comments?post=1032"}],"version-history":[{"count":3,"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/posts\/1032\/revisions"}],"predecessor-version":[{"id":1040,"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/posts\/1032\/revisions\/1040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/media\/1033"}],"wp:attachment":[{"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/media?parent=1032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/categories?post=1032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/tags?post=1032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}