{"id":1080,"date":"2021-06-29T15:34:09","date_gmt":"2021-06-29T13:34:09","guid":{"rendered":"http:\/\/www.rocalba.es\/blog\/?p=1080"},"modified":"2021-10-04T09:36:10","modified_gmt":"2021-10-04T07:36:10","slug":"solomillo-de-vaca-de-lemporda-crema-fina-de-ajo-anchoa-cebollino-y-antirrino","status":"publish","type":"post","link":"https:\/\/www.rocalba.es\/blog\/solomillo-de-vaca-de-lemporda-crema-fina-de-ajo-anchoa-cebollino-y-antirrino\/","title":{"rendered":"Solomillo de vaca de l&#8217;Empord\u00e0, crema fina de ajo, anchoa, cebollino y antirrino"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.rocalba.es\/blog\/wp-content\/themes\/veen\/assets\/images\/transparent.gif\" data-lazy=\"true\" data-src=\"http:\/\/www.rocalba.es\/blog\/wp-content\/uploads\/logo-alianca.jpg\" alt=\"\" class=\"wp-image-1082\" data-srcset=\"https:\/\/www.rocalba.es\/blog\/wp-content\/uploads\/logo-alianca.jpg 150w, https:\/\/www.rocalba.es\/blog\/wp-content\/uploads\/logo-alianca-100x100.jpg 100w, https:\/\/www.rocalba.es\/blog\/wp-content\/uploads\/logo-alianca-120x120.jpg 120w\" data-sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-left\"><strong>Restaurant L&#8217;Alian\u00e7a<\/strong><br>Calle Jacint Verdaguer, 3 Angl\u00e8s (Girona)<br><a href=\"http:\/\/www.alianca1919.com\" target=\"_blank\" rel=\"noopener\">www.alianca1919.com<\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Composici\u00f3n<\/h2>\n\n\n\n<ul><li>Solomillo de vaca de L\u2019Empord\u00e0 Salsa de ternera<\/li><li>Crema fina de ajo<\/li><li>Esferas de anchoa<\/li><li>Emulsi\u00f3n de cebollino<\/li><li>Cebollino rizado<\/li><li>Antirrino<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Solomillo de vaca de L&#8217;Empord\u00e0<\/h2>\n\n\n\n<ul><li>1 Solomillo<\/li><li>Salmuera de agua y sal al 10 % <\/li><li>Aceite de oliva<\/li><\/ul>\n\n\n\n<p>Limpiar el solomillo y ponerlo en salmuera durante 2,5 horas. Filmar y dejar reposar 24 horas. Envasar en bolsa de vac\u00edo con un poco de aceite de oliva. A la hora del pase, cocer el solomillo a 55\u00baC durante 25 min aproximadamente. Marcar por los lados, reposar y cortar por la mitad.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Salsa de ternera<\/h2>\n\n\n\n<ul><li>200 gr de huesos de ternera<\/li><li>110 gr de bresa (cebolla, zanahoria, apio y tomate)<\/li><li>2.500 gr de agua<\/li><\/ul>\n\n\n\n<p>Tostar los huesos en el horno a 180 \u00b0C durante 50 min, hasta que est\u00e9n bien dorados. Retirar el exceso de grasa y reservar. Realizar una bresa rehogando las verduras hasta que est\u00e9n bien pochadas.<br>En una olla, colocar los huesos y la bresa, cubrir con el agua fr\u00eda y cocer. Cuando el l\u00edquido se haya reducido a 1 litro, colar y reducir otra vez hasta 250 g.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Crema fina de ajo<\/h2>\n\n\n\n<ul><li>500 gr de diente de ajo pelado<\/li><li>360 gr de nata<\/li><li>Aceite de oliva<\/li><\/ul>\n\n\n\n<p>Hervir desde agua fr\u00eda los ajos por espacio de 10 minutos, a fuego lento. Escurrir y eliminar el agua. Cubrir el ajo con aceite y hervir, a fuego lento, durante otros 10 minutos. Colar y reservar por un lado el aceite, y por el otro los ajos.<br>Cubrir los ajos con la nata y volver a hervir 10 minutos a fuego lento.<br>Triturar los ajos con la nata, durante 2 minutos a m\u00e1xima potencia. A continuaci\u00f3n, montar con el aceite de la segunda cocci\u00f3n del ajo. Poner a punto de sal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Esferas de anchoa<\/h2>\n\n\n\n<ul><li>1 l de agua mineral de botella<\/li><li>7,5 gr de alginato<\/li><\/ul>\n\n\n\n<p>Mezclar bien el agua y el alginato. Debe reposar 24 horas.<\/p>\n\n\n\n<ul><li>140 gr de anchoa en aceite<\/li><li>200 gr de agua<\/li><li>5 gr de gluco<\/li><li>2 gr de xantana<\/li><\/ul>\n\n\n\n<p>Triturar todo con la batidora y colar. Con un biber\u00f3n llenar un molde de semiesfera y congelar.<\/p>\n\n\n\n<ul><li>1 semiesfera de anchoa<\/li><li>Ba\u00f1o de alg\u00edn<\/li><\/ul>\n\n\n\n<p>Atemperar el ba\u00f1o de algin (si hace falta dar un toque de microondas). Colocar las semiesferas de anchoa en el alginato 4 minutos por lado. Colocar en un tupper con agua para limpiar las esferas. Acabar colocando las esferas en un tupper con aceite de girasol.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Emulsi\u00f3n de cebollino<\/h2>\n\n\n\n<ul><li>240 gr de cebollino<\/li><li>360 gr de aceite de girasol<\/li><\/ul>\n\n\n\n<p>Triturar en Thermomix el cebollino con el aceite de girasol a m\u00e1xima potencia durante 10 minutos a 40\u00baC. Colar por chino fino sin apretar. Decantar para quitar el agua. Reservar en fr\u00edo.<\/p>\n\n\n\n<ul><li>2 yemas de huevo<\/li><li>Aceite de cebollino<\/li><li>2,2 gr de sal<\/li><\/ul>\n\n\n\n<p>Triturar el huevo y la sal y a\u00f1adir el aceite de cebollino poco a poco hasta emulsionar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cebollino rizado<\/h2>\n\n\n\n<p>Sacar bastones de cebollino y rizar con la ayuda de un cuchillo. Disponer unos segundos en agua y hielo para conseguir que se ricen m\u00e1s.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Antirrino<\/h2>\n\n\n\n<p>Sacar p\u00e9talos de antirrino.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Acabado y presentaci\u00f3n<\/h2>\n\n\n\n<p>Salsear el centro del plato con crema fina de ajo y con salsa de ternera. Colocar en medio el solomillo y, a sus laterales 2 esferas de anchoa con cebollino rizado encima. Acabar con 2 l\u00e1grimas de emulsi\u00f3n de cebollino y p\u00e9talos de antirrino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Receta elaborada con flores de Antirrino por el restaurante L&#8217;Alian\u00e7a<\/p>\n","protected":false},"author":1,"featured_media":1081,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[152],"tags":[198,200],"_links":{"self":[{"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/posts\/1080"}],"collection":[{"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/comments?post=1080"}],"version-history":[{"count":2,"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/posts\/1080\/revisions"}],"predecessor-version":[{"id":1084,"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/posts\/1080\/revisions\/1084"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/media\/1081"}],"wp:attachment":[{"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/media?parent=1080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/categories?post=1080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rocalba.es\/blog\/wp-json\/wp\/v2\/tags?post=1080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}